{"id":1257,"count":1,"description":"","link":"https:\/\/leedsname.com\/en\/t-leeds-day-trips","name":"Leeds day trips","slug":"leeds-day-trips","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/leedsname.com\/en\/wp-json\/wp\/v2\/tags\/1257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leedsname.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leedsname.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leedsname.com\/en\/wp-json\/wp\/v2\/posts?tags=1257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}