{"id":1312,"count":1,"description":"","link":"https:\/\/leedsname.com\/en\/tag\/leeds-green-spaces-2","name":"Leeds green spaces","slug":"leeds-green-spaces-2","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/leedsname.com\/en\/wp-json\/wp\/v2\/tags\/1312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leedsname.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leedsname.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leedsname.com\/en\/wp-json\/wp\/v2\/posts?tags=1312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}