{"id":1974,"count":1,"description":"","link":"https:\/\/leedsname.com\/ru\/tag\/otdyh-v-lidse","name":"\u043e\u0442\u0434\u044b\u0445 \u0432 \u041b\u0438\u0434\u0441\u0435","slug":"otdyh-v-lidse","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/tags\/1974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/posts?tags=1974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}