{"id":2242,"count":1,"description":"","link":"https:\/\/leedsname.com\/ru\/tag\/severnoe-more","name":"\u0421\u0435\u0432\u0435\u0440\u043d\u043e\u0435 \u043c\u043e\u0440\u0435","slug":"severnoe-more","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/tags\/2242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/posts?tags=2242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}