{"id":2482,"count":1,"description":"","link":"https:\/\/leedsname.com\/ru\/tag\/kooperativy","name":"\u043a\u043e\u043e\u043f\u0435\u0440\u0430\u0442\u0438\u0432\u044b","slug":"kooperativy","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/tags\/2482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/posts?tags=2482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}