{"id":371,"count":1,"description":"","link":"https:\/\/leedsname.com\/ru\/tag\/predlozheniya-dlya-uluchsheniya-ekologicheskogo-polozheniya-goroda","name":"\u041f\u0440\u0435\u0434\u043b\u043e\u0436\u0435\u043d\u0438\u044f \u0434\u043b\u044f \u0443\u043b\u0443\u0447\u0448\u0435\u043d\u0438\u044f \u044d\u043a\u043e\u043b\u043e\u0433\u0438\u0447\u0435\u0441\u043a\u043e\u0433\u043e \u043f\u043e\u043b\u043e\u0436\u0435\u043d\u0438\u044f \u0433\u043e\u0440\u043e\u0434\u0430","slug":"predlozheniya-dlya-uluchsheniya-ekologicheskogo-polozheniya-goroda","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/tags\/371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leedsname.com\/ru\/wp-json\/wp\/v2\/posts?tags=371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}