{"id":1019,"count":1,"description":"","link":"https:\/\/leedsname.com\/uk\/t-plyazh","name":"\u041f\u043b\u044f\u0436","slug":"plyazh","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/tags\/1019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/posts?tags=1019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}