{"id":1076,"count":1,"description":"","link":"https:\/\/leedsname.com\/uk\/t-leeds-brewery-istoriya","name":"Leeds Brewery \u2014 \u0456\u0441\u0442\u043e\u0440\u0456\u044f","slug":"leeds-brewery-istoriya","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/tags\/1076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/posts?tags=1076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}