{"id":2577,"count":2,"description":"","link":"https:\/\/leedsname.com\/uk\/tag\/ardsley-reservoir","name":"Ardsley Reservoir","slug":"ardsley-reservoir","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/tags\/2577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/posts?tags=2577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}