{"id":2847,"count":3,"description":"","link":"https:\/\/leedsname.com\/uk\/tag\/household-waste-recycling-centres","name":"Household Waste Recycling Centres","slug":"household-waste-recycling-centres","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/tags\/2847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leedsname.com\/uk\/wp-json\/wp\/v2\/posts?tags=2847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}